{"id":10741,"date":"2023-12-21T10:54:00","date_gmt":"2023-12-21T15:54:00","guid":{"rendered":"https:\/\/onyone.ca\/?page_id=10741"},"modified":"2024-04-21T10:18:28","modified_gmt":"2024-04-21T14:18:28","slug":"politique-de-retour","status":"publish","type":"page","link":"https:\/\/onyone.ca\/fr\/politique-de-retour\/","title":{"rendered":"Politique de retour"},"content":{"rendered":"\n<ol class=\"wp-block-list\">\n<li><strong>D\u00e9lai de retour pour les articles&nbsp;:<br><\/strong>Les retours doivent \u00eatre initi\u00e9s dans les 30 jours suivant la r\u00e9ception de la commande, tant pour les articles \u00e0 prix r\u00e9gulier que pour les \u00e9changes.<\/li>\n\n\n\n<li><strong>Articles en soldes&nbsp;:<br><\/strong>Les articles en solde sont non remboursables et non \u00e9changeables. De plus, aucun cr\u00e9dit ne peut \u00eatre \u00e9mis \u00e9galement. Veuillez-vous assurer de v\u00e9rifier soigneusement les d\u00e9tails du produit avant l&rsquo;achat.<\/li>\n\n\n\n<li><strong>\u00c9tat du produit&nbsp;:<br><\/strong>Les articles retournables et \u00e9changeables doivent \u00eatre non port\u00e9s, non lav\u00e9s et dans leur emballage d&rsquo;origine pour \u00eatre \u00e9ligibles au retour.<\/li>\n\n\n\n<li><strong>Frais de transport pour les retours&nbsp;:<\/strong><\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">Tous les frais de retour sont \u00e0 la charge du client, sauf en cas d&rsquo;erreur de notre part dans la commande.<\/p>\n\n\n\n<ol class=\"wp-block-list\" start=\"5\">\n<li><strong>\u00c9change pour un autre produit&nbsp;:<br><\/strong>Les \u00e9changes pour un autre produit peuvent \u00eatre propos\u00e9s sous r\u00e9serve de la disponibilit\u00e9 de notre inventaire. Nous pouvons \u00e9galement vous proposer un article de notre prochaine collection lorsqu&rsquo;elle sera disponible. La diff\u00e9rence de prix, le cas \u00e9ch\u00e9ant, devra \u00eatre r\u00e9gl\u00e9e par le client. Les frais de transport pour le retour de l&rsquo;article original sont \u00e0 la charge du client.<\/li>\n\n\n\n<li><strong>Essais et retours de tailles, mod\u00e8les et couleurs multiples&nbsp;:<br><\/strong>Nous encourageons nos clients \u00e0 commander avec pr\u00e9caution en v\u00e9rifiant soigneusement les tailles avant l&rsquo;achat. Les retours li\u00e9s \u00e0 des commandes de tailles, de mod\u00e8les et couleurs multiples seront accept\u00e9s, mais des frais de traitement seront appliqu\u00e9s (Frais de la plateforme Stripe et frais de transport).<\/li>\n\n\n\n<li><strong>Remboursement complet et ou partiel&nbsp;:<\/strong><\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">Pour des remboursements complets ou partiels, veuillez noter que les frais de transport du retour, les frais de la plateforme Stripe (3,7 %) ainsi que les frais de douane si applicables, seront d\u00e9duits de votre remboursement.<\/p>\n\n\n\n<ol class=\"wp-block-list\" start=\"8\">\n<li><strong>Remboursement sur le Mode de Paiement d&rsquo;Origine&nbsp;:<\/strong><\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">Les remboursements seront effectu\u00e9s sur le mode de paiement d&rsquo;origine, sauf indication contraire, et cela, avec les frais associ\u00e9s si applicables.<\/p>\n\n\n\n<ol class=\"wp-block-list\" start=\"9\">\n<li><strong>Processus de retour&nbsp;:<\/strong><\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">Les clients doivent contacter info@onyone.ca pour initier le processus de retour des articles non sold\u00e9s. Les instructions d\u00e9taill\u00e9es seront fournies \u00e0 ce moment-l\u00e0.<\/p>\n\n\n\n<ol class=\"wp-block-list\" start=\"10\">\n<li><strong>Responsabilit\u00e9 des Clients&nbsp;:<\/strong><\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">Les clients sont responsables de s&rsquo;assurer que les articles retourn\u00e9s sont correctement emball\u00e9s et exp\u00e9di\u00e9s de mani\u00e8re s\u00e9curis\u00e9e.<\/p>\n\n\n\n<ol class=\"wp-block-list\" start=\"11\">\n<li><strong>V\u00e9rification \u00e0 la R\u00e9ception&nbsp;:<\/strong><\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">Les articles retourn\u00e9s seront soumis \u00e0 une v\u00e9rification \u00e0 la r\u00e9ception, et des ajustements peuvent \u00eatre apport\u00e9s en fonction de l&rsquo;\u00e9tat r\u00e9el du produit.<\/p>\n\n\n\n<ol class=\"wp-block-list\" start=\"12\">\n<li><strong>D\u00e9lai de Traitement des Retours&nbsp;:<\/strong><\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">Le d\u00e9lai approximatif pour le traitement des retours une fois re\u00e7us est de 5 jours ouvrable.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous croyons en une approche \u00e9quitable pour tous nos clients et appr\u00e9cions votre compr\u00e9hension. N&rsquo;h\u00e9sitez pas \u00e0 nous contacter pour toute question ou pr\u00e9occupation li\u00e9e \u00e0 nos politiques.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Merci de votre confiance et de votre compr\u00e9hension.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tous les frais de retour sont \u00e0 la charge du client, sauf en cas d&rsquo;erreur de notre part dans la commande. Pour des remboursements complets ou partiels, veuillez noter que les frais de transport du retour, les frais de la plateforme Stripe (3,7 %) ainsi que les frais de douane si applicables, seront d\u00e9duits de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-template\/politique.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-10741","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Politique de retour<\/title>\n<meta name=\"description\" content=\"Politique de retour - Onyone d\u00e9lai de retour pour les articles, article en solde, conditions, frais de transport, \u00e9change, essais\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/onyone.ca\/fr\/politique-de-retour\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Politique de retour\" \/>\n<meta property=\"og:description\" content=\"Politique de retour - Onyone d\u00e9lai de retour pour les articles, article en solde, conditions, frais de transport, \u00e9change, essais\" \/>\n<meta property=\"og:url\" content=\"https:\/\/onyone.ca\/fr\/politique-de-retour\/\" \/>\n<meta property=\"og:site_name\" content=\"Onyone\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-21T14:18:28+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/onyone.ca\\\/fr\\\/politique-de-retour\\\/\",\"url\":\"https:\\\/\\\/onyone.ca\\\/fr\\\/politique-de-retour\\\/\",\"name\":\"Politique de retour\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/onyone.ca\\\/fr\\\/#website\"},\"datePublished\":\"2023-12-21T15:54:00+00:00\",\"dateModified\":\"2024-04-21T14:18:28+00:00\",\"description\":\"Politique de retour - Onyone d\u00e9lai de retour pour les articles, article en solde, conditions, frais de transport, \u00e9change, essais\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/onyone.ca\\\/fr\\\/politique-de-retour\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/onyone.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/onyone.ca\\\/fr\\\/\",\"name\":\"Onyone\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/onyone.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/onyone.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/onyone.ca\\\/fr\\\/#organization\",\"name\":\"Onyone\",\"url\":\"https:\\\/\\\/onyone.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/onyone.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/onyone.ca\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/onyone-logo.svg\",\"contentUrl\":\"https:\\\/\\\/onyone.ca\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/onyone-logo.svg\",\"width\":160,\"height\":26,\"caption\":\"Onyone\"},\"image\":{\"@id\":\"https:\\\/\\\/onyone.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Politique de retour","description":"Politique de retour - Onyone d\u00e9lai de retour pour les articles, article en solde, conditions, frais de transport, \u00e9change, essais","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/onyone.ca\/fr\/politique-de-retour\/","og_locale":"fr_FR","og_type":"article","og_title":"Politique de retour","og_description":"Politique de retour - Onyone d\u00e9lai de retour pour les articles, article en solde, conditions, frais de transport, \u00e9change, essais","og_url":"https:\/\/onyone.ca\/fr\/politique-de-retour\/","og_site_name":"Onyone","article_modified_time":"2024-04-21T14:18:28+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/onyone.ca\/fr\/politique-de-retour\/","url":"https:\/\/onyone.ca\/fr\/politique-de-retour\/","name":"Politique de retour","isPartOf":{"@id":"https:\/\/onyone.ca\/fr\/#website"},"datePublished":"2023-12-21T15:54:00+00:00","dateModified":"2024-04-21T14:18:28+00:00","description":"Politique de retour - Onyone d\u00e9lai de retour pour les articles, article en solde, conditions, frais de transport, \u00e9change, essais","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/onyone.ca\/fr\/politique-de-retour\/"]}]},{"@type":"WebSite","@id":"https:\/\/onyone.ca\/fr\/#website","url":"https:\/\/onyone.ca\/fr\/","name":"Onyone","description":"","publisher":{"@id":"https:\/\/onyone.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/onyone.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/onyone.ca\/fr\/#organization","name":"Onyone","url":"https:\/\/onyone.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/onyone.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/onyone.ca\/wp-content\/uploads\/2022\/12\/onyone-logo.svg","contentUrl":"https:\/\/onyone.ca\/wp-content\/uploads\/2022\/12\/onyone-logo.svg","width":160,"height":26,"caption":"Onyone"},"image":{"@id":"https:\/\/onyone.ca\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/onyone.ca\/fr\/wp-json\/wp\/v2\/pages\/10741","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/onyone.ca\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/onyone.ca\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/onyone.ca\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/onyone.ca\/fr\/wp-json\/wp\/v2\/comments?post=10741"}],"version-history":[{"count":0,"href":"https:\/\/onyone.ca\/fr\/wp-json\/wp\/v2\/pages\/10741\/revisions"}],"wp:attachment":[{"href":"https:\/\/onyone.ca\/fr\/wp-json\/wp\/v2\/media?parent=10741"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}